{"id":2623,"date":"2021-03-27T16:34:54","date_gmt":"2021-03-27T15:34:54","guid":{"rendered":"https:\/\/www.biauxarpajonnais.org\/?p=2623"},"modified":"2021-03-27T16:34:54","modified_gmt":"2021-03-27T15:34:54","slug":"risotto-aux-blettes","status":"publish","type":"post","link":"https:\/\/www.biauxarpajonnais.org\/index.php\/2021\/03\/27\/risotto-aux-blettes\/","title":{"rendered":"Risotto aux blettes"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"408\" height=\"348\" src=\"https:\/\/www.biauxarpajonnais.org\/wp-content\/uploads\/2021\/03\/Risotto-aux-blettes-1.jpg\" alt=\"\" class=\"wp-image-2624\" srcset=\"https:\/\/www.biauxarpajonnais.org\/wp-content\/uploads\/2021\/03\/Risotto-aux-blettes-1.jpg 408w, https:\/\/www.biauxarpajonnais.org\/wp-content\/uploads\/2021\/03\/Risotto-aux-blettes-1-300x256.jpg 300w\" sizes=\"auto, (max-width: 408px) 100vw, 408px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Ingr\u00e9dients 4 pers : <\/strong><br>300 g de blettes (feuilles et cardes)<br>300 g de riz \u00e0 risotto<br>1 l de bouillon de volaille ou de l\u00e9gumes <br>1 gros oignon<br>15 cl de vin blanc<br>1 c \u00e0 s d\u2019huile d\u2019olive <br>30 g de beurre<br>2 c \u00e0 s de mascarpone<br>80 g de parmesan r\u00e2p\u00e9<br>Sel et poivre<br><br><br><br><br><br><strong>Pr\u00e9paration ;<\/strong><br>Laver, \u00e9plucher, \u00e9mincer les c\u00f4tes et ciseler les feuilles tr\u00e8s finement. <br>Dans une cocotte, faire \u00ab tomber \u00bb (r\u00e9duire en volume) les blettes avec un fond d\u2019huile d\u2019olive. <br>Eplucher et ciseler l\u2019oignon. <br>Dans une grande casserole faire suer l\u2019oignon avec le beurre. <br>Ajouter le riz et le faire \u00ab nacrer \u00bb en remuant r\u00e9guli\u00e8rement. <br>Verser le vin blanc et faire cuire environ 5 min \u00e0 feu moyen en remuant. <br><em><strong>Pr\u00e9parer le bouillon <\/strong><\/em>: d<br>Dns un broc faire diluer le cube de bouillon dans 1L d\u2019eau bouillante. <br>Ajouter les blettes dans la casserole et bien remuer. <br>Verser peu \u00e0 peu le bouillon &#8211; \u00e0 mesure de son absorption par le riz &#8211; et remuer r\u00e9guli\u00e8rement (environ 20 min). <br>En fin de cuisson, juste avant de servir, ajouter le parmesan et le mascarpone. Bien m\u00e9langer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingr\u00e9dients 4 pers : 300 g de blettes (feuilles et cardes)300 g de riz \u00e0 risotto1 l de bouillon de volaille ou de l\u00e9gumes 1 gros oignon15 cl de vin blanc1 c \u00e0 s d\u2019huile d\u2019olive 30 g de beurre2&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-2623","post","type-post","status-publish","format-standard","hentry","category-blettes","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/posts\/2623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/comments?post=2623"}],"version-history":[{"count":0,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/posts\/2623\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/media?parent=2623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/categories?post=2623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/tags?post=2623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}