{"id":2166,"date":"2021-01-30T16:32:53","date_gmt":"2021-01-30T15:32:53","guid":{"rendered":"https:\/\/www.biauxarpajonnais.org\/?page_id=2166"},"modified":"2022-02-22T19:11:06","modified_gmt":"2022-02-22T18:11:06","slug":"radis","status":"publish","type":"page","link":"https:\/\/www.biauxarpajonnais.org\/index.php\/recettes\/radis\/","title":{"rendered":"RADIS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Plante potag\u00e8re annuelle, le radis est une racine comestible originaire d\u2019Asie mineure.&nbsp;<strong>Longues, rondes, petites ou grosses<\/strong>, les&nbsp;<strong>diff\u00e9rentes vari\u00e9t\u00e9s<\/strong>&nbsp;proposent une subtile palette de saveurs.&nbsp;<strong>Croqu\u00e9 au naturel<\/strong>&nbsp;avec un peu de sel, c\u2019est un pur aliment plaisir reconnu aussi pour ses&nbsp;<strong>qualit\u00e9s nutritionnelles<\/strong>.<br>Le radis compte parmi les premiers l\u00e9gumes cultiv\u00e9s par l\u2019homme. Le radis d\u2019aujourd\u2019hui est bien diff\u00e9rent de celui consomm\u00e9 par les \u00c9gyptiens ou les Romains.&nbsp;Il est&nbsp;<strong>cultiv\u00e9 toute l\u2019ann\u00e9e<\/strong>.<br>Des&nbsp;<strong>diff\u00e9rentes vari\u00e9t\u00e9s<\/strong>, le petit radis color\u00e9 est la plus appr\u00e9ci\u00e9e. Le gros radis noir a ses adeptes, tandis que le radis japonais devient de plus en plus populaire.<br>Faible en calories, le radis est un des l\u00e9gumes les plus riches en vitamines.<br>Surtout croqu\u00e9 cru, le radis est parfois cuit et ne jetez pas les fanes ! Cuisin\u00e9es les fanes en soupe ou velout\u00e9, tarte ou quiche, risotto, en pur\u00e9e avec des pommes de terre, ou simplement \u00e0 l\u2019\u00e9tuv\u00e9e : cuites au beurre dans une cocotte ou \u00e0 la po\u00eale. L\u00e9g\u00e8rement piquantes, subtilement am\u00e8res, elles donnent une touche herbac\u00e9e originale \u00e0 vos pr\u00e9parations. <strong>Astuce <\/strong>: Le radis aime le beurre, mais vous voulez faire l\u00e9ger cette fois ? Remplacez le par du fromage frais que vous tartinez sur une belle tranche de pain. Saupoudrez de ciboulette cisel\u00e9e ou de cerfeuil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"radis-d-hiver-noir-ou-blanc\">Radis d&rsquo;hiver noir ou blanc<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.biauxarpajonnais.org\/wp-content\/uploads\/2021\/01\/Radis-noir.jpg\" alt=\"\" class=\"wp-image-2174\" width=\"200\" height=\"150\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Le radis noir, ou radis d\u2019hiver et \u00e0 ne pas confondre avec le raifort comme c\u2019est souvent le cas, est une plante herbac\u00e9e de la famille des brassicac\u00e9es. Son petit nom latin :&nbsp;<em>Raphanus sativus var. niger<\/em>. Bon. On va continuer de l\u2019appeler radis noir. Il fait bien s\u00fbr partie de la famille des radis, dont c\u2019est la plus grosse vari\u00e9t\u00e9, mais \u00e9galement la plus forte en bouche. Il est tr\u00e8s facilement reconnaissable sur les \u00e9tals gr\u00e2ce \u00e0 sa couleur noire. Mais \u00e0 l\u2019int\u00e9rieur sa chair est blanche, certes puissante, mais d\u00e9licieuse. Par ailleurs, ses vertus sant\u00e9 reconnues lui valent un petit surnom en phytoth\u00e9rapie : c\u2019est \u00ab la plante des foies paresseux \u00bb \u2026<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"radis-blanc\">Radis blanc<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le radis gla\u00e7on est une grande racine blanche, croquante et fruit\u00e9e. Sa peau blanche et sa chair fraiche et translucide lui ont valu son nom. <br>Ressemblant au radis japonais \u00ab\u00a0da\u00efkon\u00a0\u00bb, le radis gla\u00e7on se mange r\u00e2p\u00e9 en salade ou \u00e0 la croque au sel comme les radis botte ou encore cuit comme des navets pour accompagner les viandes en sauce ou r\u00f4ties, ou des poissons.<br><strong><em>Avantage :<\/em><\/strong> r\u00e2p\u00e9, il ne s&rsquo;oxyde pas et conserve sa blancheur.<br>Le radis gla\u00e7on, cousin du radis noir, a lui aussi des propri\u00e9t\u00e9s antibact\u00e9riennes et antivirales.<br>Les Asiatiques ont l&rsquo;habitude de le pr\u00e9parer en jus. Il permet de lutter contre les probl\u00e8mes respiratoires. Le jus de radis gla\u00e7on \u00e9limine les bact\u00e9ries pr\u00e9sentes dans les poumons et garde le syst\u00e8me respiratoire sain.<br>Les enzymes que contient le radis gla\u00e7on sont semblables \u00e0 celles qui se trouvent dans notre tube digestif. Ainsi le radis gla\u00e7on permet une meilleure digestion des aliments, r\u00e9duit la constipation et d\u00e9toxifie le corps.<br>Avec sa forte concentration de vitamines C il permet de renforcer le syst\u00e8me immunitaire en stimulant la production  de globules blancs, essentiels \u00e0 notre corps.<br>En bref, le proverbe chinois <em><strong>\u00ab\u00a0Quand c&rsquo;est la saison de radis, les m\u00e9decins sont au ch\u00f4mage\u00a0\u00bb<\/strong> <\/em>est \u00e0 prendre au pied de la lettre et surtout le radis est \u00e0 consommer sans mod\u00e9ration.<\/p>\n\n\n<ul class=\"wp-block-latest-posts__list has-dates wp-block-latest-posts is-layout-flow wp-block-latest-posts-is-layout-flow\"><li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2026\/02\/15\/salade-de-betterave-crue-radis-noir-et-parsil\/\">Salade de betterave crue, radis noir et parsil<\/a><time datetime=\"2026-02-15T17:19:04+01:00\" class=\"wp-block-latest-posts__post-date\">dimanche 15 f\u00e9vrier 2026<\/time><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2025\/02\/05\/carpaccio-de-radis-dhiver\/\">Carpaccio de radis d&rsquo;hiver<\/a><time datetime=\"2025-02-05T12:22:38+01:00\" class=\"wp-block-latest-posts__post-date\">mercredi 5 f\u00e9vrier 2025<\/time><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2022\/12\/10\/salade-de-radis-dhiver-poire-et-fourme-dambert\/\">Salade de radis d&rsquo;hiver, poire et fourme d&rsquo;Ambert<\/a><time datetime=\"2022-12-10T18:59:01+01:00\" class=\"wp-block-latest-posts__post-date\">samedi 10 d\u00e9cembre 2022<\/time><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2022\/02\/22\/radis-glacon-caramelise\/\">Radis gla\u00e7on caram\u00e9lis\u00e9<\/a><time datetime=\"2022-02-22T18:44:11+01:00\" class=\"wp-block-latest-posts__post-date\">mardi 22 f\u00e9vrier 2022<\/time><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2022\/01\/30\/veloute-poireaux-et-radis-dhiver\/\">Velout\u00e9 poireaux et radis d&rsquo;hiver<\/a><time datetime=\"2022-01-30T11:23:36+01:00\" class=\"wp-block-latest-posts__post-date\">dimanche 30 janvier 2022<\/time><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2021\/01\/30\/veloute-de-radis-aux-noisettes\/\">Velout\u00e9 de radis aux noisettes<\/a><time datetime=\"2021-01-30T17:25:51+01:00\" class=\"wp-block-latest-posts__post-date\">samedi 30 janvier 2021<\/time><\/li>\n<\/ul>\n\n\n<div style=\"height:22px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"radis-rose\">Radis Rose<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"208\" height=\"164\" src=\"https:\/\/www.biauxarpajonnais.org\/wp-content\/uploads\/2021\/04\/Radis-rose.jpg\" alt=\"\" class=\"wp-image-2708\"\/><\/figure><\/div>\n\n\n<ul class=\"wp-block-latest-posts__list wp-block-latest-posts is-layout-flow wp-block-latest-posts-is-layout-flow\"><li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2021\/05\/08\/salade-de-crudites-aux-accents-exotiques\/\">Salade de crudit\u00e9s aux accents exotiques<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2021\/04\/19\/salade-de-courge-au-fromage-de-chevre\/\">Salade de courge au fromage de ch\u00e8vre<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.biauxarpajonnais.org\/index.php\/2021\/04\/10\/tarte-aux-fanes-de-radis-et-saumon-fume\/\">Tarte aux fanes de radis et saumon fum\u00e9<\/a><\/li>\n<\/ul>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plante potag\u00e8re annuelle, le radis est une racine comestible originaire d\u2019Asie mineure.&nbsp;Longues, rondes, petites ou grosses, les&nbsp;diff\u00e9rentes vari\u00e9t\u00e9s&nbsp;proposent une subtile palette de saveurs.&nbsp;Croqu\u00e9 au naturel&nbsp;avec un peu de sel, c\u2019est un pur aliment plaisir reconnu aussi pour ses&nbsp;qualit\u00e9s nutritionnelles.Le radis&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":54,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2166","page","type-page","status-publish","hentry","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/pages\/2166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/comments?post=2166"}],"version-history":[{"count":1,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/pages\/2166\/revisions"}],"predecessor-version":[{"id":4058,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/pages\/2166\/revisions\/4058"}],"up":[{"embeddable":true,"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/pages\/54"}],"wp:attachment":[{"href":"https:\/\/www.biauxarpajonnais.org\/index.php\/wp-json\/wp\/v2\/media?parent=2166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}